{"id":40372,"date":"2025-02-10T12:26:00","date_gmt":"2025-02-10T11:26:00","guid":{"rendered":"https:\/\/www.sics.it\/?page_id=40372"},"modified":"2026-03-23T09:40:56","modified_gmt":"2026-03-23T08:40:56","slug":"corso-osservatore-calcistico","status":"publish","type":"page","link":"https:\/\/www.sics.it\/en\/corso-osservatore-calcistico\/","title":{"rendered":"Corso Osservatore Calcistico"},"content":{"rendered":"<div data-elementor-type=\"wp-post\" data-elementor-id=\"40372\" class=\"elementor elementor-40372\">\n\t\t\t\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-a1b8a8e elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"a1b8a8e\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-6960540\" data-id=\"6960540\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-37d451f elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"37d451f\" data-element_type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4584bdc elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"4584bdc\" data-element_type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-13cd23e elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"13cd23e\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-8f3fe3e\" data-id=\"8f3fe3e\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-54380e3 elementor-widget elementor-widget-image\" data-id=\"54380e3\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" width=\"1024\" height=\"404\" src=\"https:\/\/www.sics.it\/wp-content\/uploads\/2026\/02\/Corso-Osservatori-3-2048-x-808-px-1024x404.png\" class=\"attachment-large size-large wp-image-43749\" alt=\"\" srcset=\"https:\/\/www.sics.it\/wp-content\/uploads\/2026\/02\/Corso-Osservatori-3-2048-x-808-px-1024x404.png 1024w, https:\/\/www.sics.it\/wp-content\/uploads\/2026\/02\/Corso-Osservatori-3-2048-x-808-px-300x118.png 300w, https:\/\/www.sics.it\/wp-content\/uploads\/2026\/02\/Corso-Osservatori-3-2048-x-808-px-768x303.png 768w, https:\/\/www.sics.it\/wp-content\/uploads\/2026\/02\/Corso-Osservatori-3-2048-x-808-px-1536x606.png 1536w, https:\/\/www.sics.it\/wp-content\/uploads\/2026\/02\/Corso-Osservatori-3-2048-x-808-px-18x7.png 18w, https:\/\/www.sics.it\/wp-content\/uploads\/2026\/02\/Corso-Osservatori-3-2048-x-808-px-1200x473.png 1200w, https:\/\/www.sics.it\/wp-content\/uploads\/2026\/02\/Corso-Osservatori-3-2048-x-808-px-600x237.png 600w, https:\/\/www.sics.it\/wp-content\/uploads\/2026\/02\/Corso-Osservatori-3-2048-x-808-px.png 2048w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-6262c30 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"6262c30\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-d9b9c37\" data-id=\"d9b9c37\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2de48da elementor-widget elementor-widget-text-editor\" data-id=\"2de48da\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<span style=\"font-family: Arial, sans-serif;\"><span style=\"white-space-collapse: preserve;\"><span style=\"font-weight: bold;\">CORSO OSSERVATORE CALCISTICO &#8211; <\/span><\/span><\/span><span style=\"font-size: 12pt; white-space-collapse: preserve; font-family: Arial, sans-serif;\"><span style=\"font-size: 12pt; background-color: transparent; font-weight: bold; font-variant-numeric: normal; font-variant-east-asian: normal; font-variant-alternates: normal; font-variant-position: normal; font-variant-emoji: normal; vertical-align: baseline;\">METODOLOGIE DI OSSERVAZIONE E UTILIZZO DEI DATI NELLO SCOUTING CALCISTICO MODERNO<\/span><\/span>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-be3263b elementor-hidden-desktop elementor-hidden-tablet elementor-hidden-mobile elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"be3263b\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-ce29065\" data-id=\"ce29065\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-e8df36d\" data-id=\"e8df36d\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-90288ae elementor-align-center elementor-widget elementor-widget-button\" data-id=\"90288ae\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-md\" href=\"https:\/\/www.sics.it\/en\/product\/acconto-corso-osservatore-calcistico\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-text\">SIGN UP<\/span>\n\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-c3fa29e\" data-id=\"c3fa29e\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-75361df elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"75361df\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-43b60d6\" data-id=\"43b60d6\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d1a95ea elementor-widget elementor-widget-text-editor\" data-id=\"d1a95ea\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p style=\"text-align: center;\"><span style=\"color: #ff0000;\"><strong>REGISTRATIONS ARE CLOSED<\/strong><\/span><\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-b6ff38e elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"b6ff38e\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-45c5b18\" data-id=\"45c5b18\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-45ba676 elementor-widget elementor-widget-text-editor\" data-id=\"45ba676\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p><span style=\"background-color: transparent; font-size: 12pt; font-family: Arial, sans-serif; font-weight: bold; font-variant-numeric: normal; font-variant-east-asian: normal; font-variant-alternates: normal; font-variant-position: normal; font-variant-emoji: normal; vertical-align: baseline; white-space-collapse: preserve;\">SICS <\/span><span style=\"background-color: transparent; font-size: 12pt; font-family: Arial, sans-serif; font-variant-numeric: normal; font-variant-east-asian: normal; font-variant-alternates: normal; font-variant-position: normal; font-variant-emoji: normal; vertical-align: baseline; white-space-collapse: preserve;\">organizza la seconda edizione della nuova serie di Corsi dedicati al <\/span><span style=\"background-color: transparent; font-size: 12pt; font-family: Arial, sans-serif; font-weight: bold; font-variant-numeric: normal; font-variant-east-asian: normal; font-variant-alternates: normal; font-variant-position: normal; font-variant-emoji: normal; vertical-align: baseline; white-space-collapse: preserve;\">\u201cFootball Scouting\u201d.<\/span><\/p><p><span style=\"font-size: 12pt; font-family: Arial, sans-serif; background-color: transparent; font-variant-numeric: normal; font-variant-east-asian: normal; font-variant-alternates: normal; font-variant-position: normal; font-variant-emoji: normal; vertical-align: baseline; white-space-collapse: preserve;\">Il primo Corso di questa serie si \u00e8 tenuto a Maggio 2025, in questo secondo corso sono state introdotte significative novit\u00e0 quali la possibilt\u00e0 di stage per i migliori classificati oltre a un importante contributo con testimonianze di illustri ospiti provenienti dallo scouting professionistico<\/span><span style=\"font-size: 12pt; font-family: Arial, sans-serif; background-color: transparent; font-variant-numeric: normal; font-variant-east-asian: normal; font-variant-alternates: normal; font-variant-position: normal; font-variant-emoji: normal; vertical-align: baseline; white-space-collapse: preserve;\">.<\/span><\/p><p><span style=\"font-size: 12pt; font-family: Arial, sans-serif; background-color: transparent; font-variant-numeric: normal; font-variant-east-asian: normal; font-variant-alternates: normal; font-variant-position: normal; font-variant-emoji: normal; vertical-align: baseline; white-space-collapse: preserve;\">Il corso \u201c<\/span><span style=\"font-size: 12pt; font-family: Arial, sans-serif; background-color: transparent; font-weight: bold; font-variant-numeric: normal; font-variant-east-asian: normal; font-variant-alternates: normal; font-variant-position: normal; font-variant-emoji: normal; vertical-align: baseline; white-space-collapse: preserve;\">Osservatore Calcistico<\/span><span style=\"font-size: 12pt; font-family: Arial, sans-serif; background-color: transparent; font-variant-numeric: normal; font-variant-east-asian: normal; font-variant-alternates: normal; font-variant-position: normal; font-variant-emoji: normal; vertical-align: baseline; white-space-collapse: preserve;\">\u201d sar\u00e0 interamente online e consentir\u00e0 la frequenza alle lezioni\u00a0 (e al relativo esame) da remoto comodamente da casa propria o dal proprio ufficio.<\/span><\/p><p dir=\"ltr\" style=\"line-height: 1.38; background-color: #f9f9f9; margin-top: 0pt; margin-bottom: 19pt;\"><span style=\"font-size: 12pt; font-family: Arial,sans-serif; color: #595959; background-color: transparent; font-weight: 400; font-style: normal; font-variant: normal; text-decoration: none; vertical-align: baseline; white-space: pre-wrap;\">Il corso prevede un esame finale che una volta superato consentir\u00e0 ai partecipanti di ottenere la <\/span><span style=\"font-size: 12pt; font-family: Arial,sans-serif; color: #595959; background-color: transparent; font-weight: bold; font-style: normal; font-variant: normal; text-decoration: none; vertical-align: baseline; white-space: pre-wrap;\">certificazione e l\u2019iscrizione all\u2019Albo \u201cOsservatore Calcistico SICS\u201d<\/span><span style=\"font-size: 12pt; font-family: Arial,sans-serif; color: #595959; background-color: transparent; font-weight: 400; font-style: normal; font-variant: normal; text-decoration: none; vertical-align: baseline; white-space: pre-wrap;\"> che sar\u00e0 adeguatamente pubblicizzato per diventare a tutti gli effetti un riferimento dei club professionistici e delle Agenzie di Scouting nella creazione e gestione della propria rete di osservatori.<\/span><\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-94ca312 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"94ca312\" data-element_type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-267a818 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"267a818\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-cb129d9\" data-id=\"cb129d9\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5f51ac3 elementor-widget elementor-widget-heading\" data-id=\"5f51ac3\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Duration<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c5fa04b elementor-widget elementor-widget-text-editor\" data-id=\"c5fa04b\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul><li><strong>60 ore totali<\/strong> organizzate in 42 ore di lezioni online articolate su 14 giornate: 12 sessioni di 3 ore ciascuna, la sera dalle 18:30 alle 22 con esame finale\u00a0 per conseguire la certificazione<\/li><li>18 ore di home working con<strong> tutor dedicato<\/strong> sullo studio approfondito di un campionato\u00a0 per l&#8217;individuazione e la presentazione di\u00a0 possibili talenti\u00a0<\/li><\/ul>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-0dbce59\" data-id=\"0dbce59\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-9f805d2 elementor-widget elementor-widget-heading\" data-id=\"9f805d2\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Program<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3e73224 elementor-widget elementor-widget-text-editor\" data-id=\"3e73224\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul style=\"margin-top: 0!important;\"><li>Talent ID &amp; Reporting (<strong>Antonio Larocca<\/strong> 7 ore)<\/li><li>Metodologia dello scouting e del recruitment (<strong>Leonardo Mantovani <\/strong>2 ore)<\/li><li>Tattica Calcistica individuale (<span style=\"font-weight: bold;\">Francesco Bordin <\/span>3\u00a0ore)<\/li><li>Utilizzo di piattaforme per lo scouting (<span style=\"font-weight: bold;\">Marco Carniel <\/span>4 ore)<\/li><li>Testimonianze e Lezioni di vari professionisti del settore (20 ore)<\/li><li>Tutoraggio personalizzato su esercitazioni individuali (18 ore)<\/li><li>Esame (6 ore)<\/li><\/ul>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-0c8a607 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"0c8a607\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-b0340b2\" data-id=\"b0340b2\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-27bdd20 elementor-widget elementor-widget-heading\" data-id=\"27bdd20\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Timetable<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-17728b2 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"17728b2\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-529b808\" data-id=\"529b808\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2480730 elementor-widget elementor-widget-text-editor\" data-id=\"2480730\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p><strong>N.B.<\/strong> Participation in lessons must be live<br \/>E&#8217; consentito un massimo di quattro assenze, le lezioni perse potranno essere recuperate on-demand.<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-1dd92fd elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"1dd92fd\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-8b16daf\" data-id=\"8b16daf\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4948df7 elementor-widget elementor-widget-text-editor\" data-id=\"4948df7\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p style=\"text-align: center;\"><strong>Luned\u00ec 23 Marzo<\/strong><br \/>18:30 &#8211; 22:00<br \/>Presentazione Corso, Introduzione allo scouting professionale, Piattaforme Scouting (1\/4)\u00a0<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-33d3215\" data-id=\"33d3215\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5560735 elementor-widget elementor-widget-text-editor\" data-id=\"5560735\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p style=\"text-align: center;\"><span style=\"font-weight: bold;\">Wednesday<\/span><span style=\"font-weight: bold;\">\u00a025 Marzo<\/span><br \/>18:30 &#8211; 22:00<br \/>Metodologia dello scouting<br \/>Piattaforme scouting (2\/4)<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-d18e006\" data-id=\"d18e006\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1b111d8 elementor-widget elementor-widget-text-editor\" data-id=\"1b111d8\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p style=\"text-align: center;\"><span style=\"font-weight: bold;\">Venerd\u00ec<\/span><b>\u00a027 Marzo<br \/><\/b>18:30 &#8211; 22:00<br \/>Talent ID (1\/4)<br \/>Processo di selezione calciatori<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-5c7c7f7 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"5c7c7f7\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-7a3e55a\" data-id=\"7a3e55a\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-19c2407 elementor-widget elementor-widget-text-editor\" data-id=\"19c2407\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p style=\"text-align: center;\"><span style=\"font-weight: bold;\">Luned\u00ec<\/span><span style=\"font-weight: bold;\">\u00a030 Marzo<\/span><br \/>18:30 &#8211; 22:00<br \/>Talent ID (2\/4)<br \/>Tattica Individuale (1\/2)<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-6a07aa1\" data-id=\"6a07aa1\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-593df45 elementor-widget elementor-widget-text-editor\" data-id=\"593df45\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p style=\"text-align: center;\"><strong>Mercoled\u00ec 1 Aprile<\/strong><br \/>18:30 &#8211; 22:00<br \/>Piattaforme scouting (3\/4)<br \/>Tattica Individuale (2\/2)<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-c5b5e3e\" data-id=\"c5b5e3e\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-01d0553 elementor-widget elementor-widget-text-editor\" data-id=\"01d0553\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p style=\"text-align: center;\"><b>Mercoled\u00ec 8 Aprile<\/b><b><br \/><\/b>18:30 &#8211; 22:00<br \/>Lo scouting del Club Italia<br \/>Lo scouting nel settore giovanile<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-647ab09 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"647ab09\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-84dcab9\" data-id=\"84dcab9\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-cbc271b elementor-widget elementor-widget-text-editor\" data-id=\"cbc271b\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p style=\"text-align: center;\"><span style=\"font-weight: bold;\">Venerd\u00ec 10 Aprile<\/span><br \/>18:30 &#8211; 22:00<br \/>Lo Scouting nel Club Italia<br \/>Organizzazione della struttura di scouting in un club professionistico<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-b7dd3b9\" data-id=\"b7dd3b9\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-41ca7e7 elementor-widget elementor-widget-text-editor\" data-id=\"41ca7e7\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p style=\"text-align: center;\"><b>Luned\u00ec 13 Aprile<br \/><\/b>18:30 &#8211; 22:00<br \/>Talent ID (3\/4)<br \/>Piattaforme scouting (4\/4)<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-2cc9c5b\" data-id=\"2cc9c5b\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-903b95f elementor-widget elementor-widget-text-editor\" data-id=\"903b95f\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p style=\"text-align: center;\"><span style=\"font-weight: bold;\">Mercoled\u00ec 15 Aprile<\/span><b><br \/><\/b>18:30 &#8211; 22:00<br \/>Testimonianza di un Direttore Sportivo Top<br \/>Scouting e Intelligenza Artificiale<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-0f6001a elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"0f6001a\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-75f3506\" data-id=\"75f3506\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ccbaeb6 elementor-widget elementor-widget-text-editor\" data-id=\"ccbaeb6\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p style=\"text-align: center;\"><b>Venerd\u00ec 17 Aprile<br \/><\/b>18:30 &#8211; 22:00<br \/>Talent ID (4\/4)<br \/>Utilizzo dei dati fisici per lo Scouting<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-2491b33\" data-id=\"2491b33\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3a1b1ba elementor-widget elementor-widget-text-editor\" data-id=\"3a1b1ba\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p style=\"text-align: center;\"><b>Luned\u00ec 20 Aprile<\/b><br \/>18:30 &#8211; 22:00<br \/>Lo Scouting Internazionale, metodologia di un Top Club europeo\u00a0<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-6e7192e\" data-id=\"6e7192e\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c9c3893 elementor-widget elementor-widget-text-editor\" data-id=\"c9c3893\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p style=\"text-align: center;\"><b>Mercoled\u00ec 22 Aprile<\/b><b><br \/><\/b>18:30 &#8211; 22:00<br \/>Scouting, Comunicazione e Psicologia<br \/>Gli Agenti dei calciatori e lo Scouting<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-a01aaa0 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"a01aaa0\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-17e776f\" data-id=\"17e776f\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f3ee90e elementor-widget elementor-widget-text-editor\" data-id=\"f3ee90e\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p style=\"text-align: center;\"><strong>Sabato 9 Maggio<\/strong><br \/>Orario da definire<br \/>FINAL EXAM<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-d42a36a elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"d42a36a\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-568da5d\" data-id=\"568da5d\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6e3eeea elementor-widget elementor-widget-text-editor\" data-id=\"6e3eeea\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<h5><strong>Prerequisites<\/strong><\/h5><p>Good knowledge and use of computer.\u00a0<br \/>Il corso \u00e8 di tipo teorico\/pratico; i partecipanti dovranno utilizzare un proprio PC con una buona connessione a internet, per accedere alle piattaforme online messe a disposizione da SICS.<\/p><p>Non \u00e8 richiesto alcun un diploma di Allenatore o Osservatore ma \u00e8 consigliata una buona conoscenza dei fondamenti di tecnica, tattica e della terminologia calcistica\u00a0 \u00a0<\/p><h5><strong>Participants will be provided with:<\/strong><\/h5><ul><li>Accesso per 3 mesi alla piattaforma professionale di scouting video\/dati\u00a0<b>SICS.tv<\/b><\/li><li>Accesso per 3 mesi alla piattaforma professionale di data analisi (giocatori e squadre)\u00a0<span style=\"font-weight: bold;\">SICS Data Analytics<\/span><\/li><li>Certificate of participation in the course<\/li><\/ul>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-1395eae elementor-hidden-phone elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"1395eae\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-a108297 elementor-hidden-desktop elementor-hidden-tablet\" data-id=\"a108297\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1fa4377 elementor-widget elementor-widget-heading\" data-id=\"1fa4377\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Teachers<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-0f6a363 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"0f6a363\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-3998dfb\" data-id=\"3998dfb\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7e6ccde elementor-widget elementor-widget-image\" data-id=\"7e6ccde\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img width=\"1024\" height=\"366\" src=\"https:\/\/www.sics.it\/wp-content\/uploads\/2025\/12\/Docenti-corso-Osservatori-1024x366.png\" class=\"attachment-large size-large wp-image-43262\" alt=\"\" srcset=\"https:\/\/www.sics.it\/wp-content\/uploads\/2025\/12\/Docenti-corso-Osservatori-1024x366.png 1024w, https:\/\/www.sics.it\/wp-content\/uploads\/2025\/12\/Docenti-corso-Osservatori-300x107.png 300w, https:\/\/www.sics.it\/wp-content\/uploads\/2025\/12\/Docenti-corso-Osservatori-768x274.png 768w, https:\/\/www.sics.it\/wp-content\/uploads\/2025\/12\/Docenti-corso-Osservatori-1536x548.png 1536w, https:\/\/www.sics.it\/wp-content\/uploads\/2025\/12\/Docenti-corso-Osservatori-18x6.png 18w, https:\/\/www.sics.it\/wp-content\/uploads\/2025\/12\/Docenti-corso-Osservatori-1200x428.png 1200w, https:\/\/www.sics.it\/wp-content\/uploads\/2025\/12\/Docenti-corso-Osservatori-600x214.png 600w, https:\/\/www.sics.it\/wp-content\/uploads\/2025\/12\/Docenti-corso-Osservatori.png 2048w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-106880c elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"106880c\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-702baee\" data-id=\"702baee\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-fb32497 elementor-widget elementor-widget-heading\" data-id=\"fb32497\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Certification<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1e247c6 elementor-widget elementor-widget-text-editor\" data-id=\"1e247c6\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>The participants who pass the final exam will be provided with:<\/p><ul style=\"list-style-type: disc;\"><li>Attestato\u00a0<strong>Osservatore Calcistico\u00a0<\/strong><span style=\"font-weight: bold;\">SICS\u00a0<\/span><\/li><li>Iscrizione all\u2019albo <b>Osservatori Calcistici SICS<\/b><\/li><li>All\u2019albo e ai nominativi degli iscritti verranno dati ampio risalto e visibilit\u00e0 presso i club professionistici e le agenzie di scouting internazionali.<\/li><\/ul>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-683e01b\" data-id=\"683e01b\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-8337fbe elementor-widget elementor-widget-heading\" data-id=\"8337fbe\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Costs<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-35c88d0 elementor-widget__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"35c88d0\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>Al fine di premiare le sottoscrizioni anticipate, sono previste 3 fasce di prezzo per le iscrizioni effettuate:<\/p><p><span style=\"font-weight: bold;\">Entro il 20 Gennaio:<\/span>\u00a0\u20ac990<br \/><span style=\"font-weight: bold;\">Dal 21 Gennaio al 22 Febbraio:<\/span>\u00a0\u20ac1.090<br \/><br \/><\/p><p>(anticipo da pagare al momento dell\u2019iscrizione e saldo in unica soluzione o, fino al 15 Febbraio, in 2 rate, con un piccolo sovrapprezzo di 30\u20ac).<\/p><p><span style=\"font-weight: bold;\">N.B.<\/span>\u00a0L\u2019iscrizione sar\u00e0 considerata effettiva esclusivamente al momento del versamento dell\u2019anticipo<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-c25d248 elementor-hidden-desktop elementor-hidden-tablet elementor-hidden-mobile elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"c25d248\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-659f66c\" data-id=\"659f66c\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-8cb1e63 elementor-widget__width-initial elementor-widget elementor-widget-heading\" data-id=\"8cb1e63\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\"><div style=\"text-align: justify;\"><span style=\"white-space-collapse: collapse;\">&nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; &nbsp; Stage<\/span><\/div><\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c81e853 elementor-widget__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"c81e853\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>Ai migliori corsisti viene data la possibilit\u00e0 di effettuare un periodo di stage all&#8217;interno dell&#8217;area scouting di:<\/p><ul><li>Fiorentina<\/li><li>Modena<\/li><li>Pro Vercelli<\/li><li>Napoli Women<\/li><\/ul>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-0b89089 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"0b89089\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-a1ed096\" data-id=\"a1ed096\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c87c583 elementor-widget elementor-widget-heading\" data-id=\"c87c583\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\"><span style=\"text-align: justify; white-space-collapse: collapse;\">FAQ e info aggiuntive<\/span><\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-716a815 elementor-widget elementor-widget-text-editor\" data-id=\"716a815\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>Al\u00a0<span style=\"text-align: justify;\">seguente link \u00e8 possibile consultare tutte le informazioni dettagliate relative al corso:\u00a0<\/span><a style=\"text-align: justify;\" href=\"https:\/\/www.sics.it\/wp-content\/uploads\/2025\/03\/Presentazione-Corso-Osservatore.pdf\">FAQ<\/a><\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-c2cd0e0 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"c2cd0e0\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-db173e5\" data-id=\"db173e5\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d1b7119 elementor-widget elementor-widget-heading\" data-id=\"d1b7119\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Join the course<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-474dea9 elementor-widget elementor-widget-text-editor\" data-id=\"474dea9\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p class=\" translation-block\">At the time of registration you will be asked to pay an advance of \u20ac190.00. It is possible to pay by credit card or bank transfer.<\/p>\n<p>You will immediately receive an mail  confirming the registration to the course.<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-1aa1e07 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"1aa1e07\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-08e4f54\" data-id=\"08e4f54\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ec54c7f elementor-widget elementor-widget-text-editor\" data-id=\"ec54c7f\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p style=\"text-align: center;\"><span style=\"color: #ff0000;\"><strong>REGISTRATIONS ARE CLOSED<\/strong><\/span><\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-477c135 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"477c135\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-861151c\" data-id=\"861151c\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-fdc1c47 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"fdc1c47\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-7bad2c0\" data-id=\"7bad2c0\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c44e388 elementor-widget elementor-widget-text-editor\" data-id=\"c44e388\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<h5 style=\"margin-bottom: 0px;\">Acconto Corso Osservatore Calcistico<\/h5><p>Iscriviti al Corso Osservatore Calcistico (\u20ac 190,00)<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-c9158ae\" data-id=\"c9158ae\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-20376a5 elementor-align-center elementor-hidden-desktop elementor-hidden-tablet elementor-hidden-mobile elementor-widget elementor-widget-button\" data-id=\"20376a5\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-md\" href=\"https:\/\/www.sics.it\/en\/product\/acconto-corso-osservatore-calcistico\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-text\">SIGN UP<\/span>\n\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-17407ae elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"17407ae\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-51933a4\" data-id=\"51933a4\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-8cfed09 elementor-widget elementor-widget-text-editor\" data-id=\"8cfed09\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<h6 style=\"padding-left: 40px;\"><br><\/h6>\n<h6><strong>Cancellation policy<\/strong><br>SICS si riserva la facolt\u00e0 di annullare il corso in caso di mancato raggiungimento del numero minimo di 20 iscritti, gli acconti versati verranno restituiti solo in tal caso<\/h6>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>CORSO OSSERVATORE CALCISTICO &#8211; METODOLOGIE DI OSSERVAZIONE E UTILIZZO DEI DATI NELLO SCOUTING CALCISTICO MODERNO EFFETTUA ISCRIZIONE LE ISCRIZIONI SONO CHIUSE SICS organizza la seconda edizione della nuova serie di Corsi dedicati al \u201cFootball Scouting\u201d. Il primo Corso di questa serie si \u00e8 tenuto a Maggio 2025, in questo secondo corso sono state introdotte significative [&hellip;]<\/p>","protected":false},"author":3,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_starter_page_template":"","_wpcom_template_layout_category":[]},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v19.7.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Corso Osservatore Calcistico - Sics<\/title>\n<meta name=\"description\" content=\"Il corso Osservatore Calcistico interamente Online per l&#039;abilitazione e l&#039;iscrizione all&#039;albo osservatori SICS\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.sics.it\/en\/corso-osservatore-calcistico\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Corso Osservatore Calcistico - Sics\" \/>\n<meta property=\"og:description\" content=\"Il corso Osservatore Calcistico interamente Online per l&#039;abilitazione e l&#039;iscrizione all&#039;albo osservatori SICS\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.sics.it\/en\/corso-osservatore-calcistico\/\" \/>\n<meta property=\"og:site_name\" content=\"Sics\" \/>\n<meta property=\"article:modified_time\" content=\"2026-03-23T08:40:56+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.sics.it\/wp-content\/uploads\/2026\/02\/Corso-Osservatori-3-2048-x-808-px-1024x404.png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"5 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.sics.it\/corso-osservatore-calcistico\/\",\"url\":\"https:\/\/www.sics.it\/corso-osservatore-calcistico\/\",\"name\":\"Corso Osservatore Calcistico - Sics\",\"isPartOf\":{\"@id\":\"https:\/\/www.sics.it\/en\/#website\"},\"datePublished\":\"2025-02-10T11:26:00+00:00\",\"dateModified\":\"2026-03-23T08:40:56+00:00\",\"description\":\"Il corso Osservatore Calcistico interamente Online per l'abilitazione e l'iscrizione all'albo osservatori SICS\",\"breadcrumb\":{\"@id\":\"https:\/\/www.sics.it\/corso-osservatore-calcistico\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.sics.it\/corso-osservatore-calcistico\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.sics.it\/corso-osservatore-calcistico\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.sics.it\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Corso Osservatore Calcistico\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.sics.it\/en\/#website\",\"url\":\"https:\/\/www.sics.it\/en\/\",\"name\":\"Sics\",\"description\":\"Match Analysis, Planning and Monitoring\",\"publisher\":{\"@id\":\"https:\/\/www.sics.it\/en\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.sics.it\/en\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.sics.it\/en\/#organization\",\"name\":\"Sics - Match Analysis, Training Control, Performance Monitoring & Measurement\",\"url\":\"https:\/\/www.sics.it\/en\/\",\"sameAs\":[],\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/www.sics.it\/en\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.sics.it\/wp-content\/uploads\/2019\/11\/sics-logo-03.png\",\"contentUrl\":\"https:\/\/www.sics.it\/wp-content\/uploads\/2019\/11\/sics-logo-03.png\",\"width\":4724,\"height\":1181,\"caption\":\"Sics - Match Analysis, Training Control, Performance Monitoring & Measurement\"},\"image\":{\"@id\":\"https:\/\/www.sics.it\/en\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Corso Osservatore Calcistico - Sics","description":"Il corso Osservatore Calcistico interamente Online per l'abilitazione e l'iscrizione all'albo osservatori SICS","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.sics.it\/en\/corso-osservatore-calcistico\/","og_locale":"en_US","og_type":"article","og_title":"Corso Osservatore Calcistico - Sics","og_description":"Il corso Osservatore Calcistico interamente Online per l'abilitazione e l'iscrizione all'albo osservatori SICS","og_url":"https:\/\/www.sics.it\/en\/corso-osservatore-calcistico\/","og_site_name":"Sics","article_modified_time":"2026-03-23T08:40:56+00:00","og_image":[{"url":"https:\/\/www.sics.it\/wp-content\/uploads\/2026\/02\/Corso-Osservatori-3-2048-x-808-px-1024x404.png"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"5 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.sics.it\/corso-osservatore-calcistico\/","url":"https:\/\/www.sics.it\/corso-osservatore-calcistico\/","name":"Corso Osservatore Calcistico - Sics","isPartOf":{"@id":"https:\/\/www.sics.it\/en\/#website"},"datePublished":"2025-02-10T11:26:00+00:00","dateModified":"2026-03-23T08:40:56+00:00","description":"Il corso Osservatore Calcistico interamente Online per l'abilitazione e l'iscrizione all'albo osservatori SICS","breadcrumb":{"@id":"https:\/\/www.sics.it\/corso-osservatore-calcistico\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.sics.it\/corso-osservatore-calcistico\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.sics.it\/corso-osservatore-calcistico\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.sics.it\/"},{"@type":"ListItem","position":2,"name":"Corso Osservatore Calcistico"}]},{"@type":"WebSite","@id":"https:\/\/www.sics.it\/en\/#website","url":"https:\/\/www.sics.it\/en\/","name":"Sics","description":"Match Analysis, Planning and Monitoring","publisher":{"@id":"https:\/\/www.sics.it\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.sics.it\/en\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.sics.it\/en\/#organization","name":"Sics - Match Analysis, Training Control, Performance Monitoring & Measurement","url":"https:\/\/www.sics.it\/en\/","sameAs":[],"logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.sics.it\/en\/#\/schema\/logo\/image\/","url":"https:\/\/www.sics.it\/wp-content\/uploads\/2019\/11\/sics-logo-03.png","contentUrl":"https:\/\/www.sics.it\/wp-content\/uploads\/2019\/11\/sics-logo-03.png","width":4724,"height":1181,"caption":"Sics - Match Analysis, Training Control, Performance Monitoring & Measurement"},"image":{"@id":"https:\/\/www.sics.it\/en\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.sics.it\/en\/wp-json\/wp\/v2\/pages\/40372"}],"collection":[{"href":"https:\/\/www.sics.it\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.sics.it\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.sics.it\/en\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.sics.it\/en\/wp-json\/wp\/v2\/comments?post=40372"}],"version-history":[{"count":175,"href":"https:\/\/www.sics.it\/en\/wp-json\/wp\/v2\/pages\/40372\/revisions"}],"predecessor-version":[{"id":43995,"href":"https:\/\/www.sics.it\/en\/wp-json\/wp\/v2\/pages\/40372\/revisions\/43995"}],"wp:attachment":[{"href":"https:\/\/www.sics.it\/en\/wp-json\/wp\/v2\/media?parent=40372"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}